{"id":274,"date":"2018-02-18T00:19:12","date_gmt":"2018-02-17T23:19:12","guid":{"rendered":"https:\/\/www.hemiparesis-therapy.com\/?p=274"},"modified":"2024-06-19T11:06:17","modified_gmt":"2024-06-19T09:06:17","slug":"18-02-18-die-entwicklungsarbeiten-fuer-unseren-marktreifen-prototypen-remod-v5-0-sind-abgeschlossen","status":"publish","type":"post","link":"https:\/\/www.hemiparesis-therapy.com\/index.php\/2018\/02\/18\/18-02-18-die-entwicklungsarbeiten-fuer-unseren-marktreifen-prototypen-remod-v5-0-sind-abgeschlossen\/","title":{"rendered":"18.02.18 Die Entwicklungsarbeiten f\u00fcr unseren marktreifen Prototypen ReMoD V5.0 sind abgeschlossen!"},"content":{"rendered":"<p>Mit den Geldern und der Unterst\u00fctzung aus \u2018\u2019Die H\u00f6hle der L\u00f6wen\u2019\u2019 haben wir uns als erstes damit besch\u00e4ftigt, das Ger\u00e4t ReMoD nach unseren genauen Vorstellungen fertig zu entwickeln. Wir wollten, dass das neue ReMoD V5.0 so vielseitig wie m\u00f6glich angewendet werden kann, da auch jedes Krankheitsbild sehr viele Gesichter hat. Endlich sind die Entwicklungen abgeschlossen und wir sind im Prozess der Zulassung als Medizinprodukt \u2013 und\u00a0diese Dokumentationen sind weitaus\u00a0mehr Arbeit als die ganze Entwicklung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit den Geldern und der Unterst\u00fctzung aus \u2018\u2019Die H\u00f6hle der L\u00f6wen\u2019\u2019 haben wir uns als erstes damit besch\u00e4ftigt, das Ger\u00e4t ReMoD nach unseren genauen Vorstellungen fertig zu entwickeln. Wir wollten, dass das neue ReMoD V5.0 so vielseitig wie m\u00f6glich angewendet werden kann, da auch jedes Krankheitsbild sehr viele Gesichter hat. Endlich sind die Entwicklungen abgeschlossen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/posts\/274"}],"collection":[{"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/comments?post=274"}],"version-history":[{"count":1,"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/posts\/274\/revisions"}],"predecessor-version":[{"id":275,"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/posts\/274\/revisions\/275"}],"wp:attachment":[{"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/media?parent=274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/categories?post=274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hemiparesis-therapy.com\/index.php\/wp-json\/wp\/v2\/tags?post=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}